{"id":16487,"date":"2025-11-30T06:02:54","date_gmt":"2025-11-30T05:02:54","guid":{"rendered":"https:\/\/paperwise.eu\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/"},"modified":"2026-05-20T06:11:38","modified_gmt":"2026-05-20T04:11:38","slug":"il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente","status":"publish","type":"post","link":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/","title":{"rendered":"Il coronavirus causa un calo del fatturato, ma anche benefici per l&#8217;ambiente"},"content":{"rendered":"\n<section class=\"section-hero-paperwise text-color-light\" >\n    <div class=\"hero-background \" style=\"background-image: url('https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg');\">\n\n        \n        <div class=\"container-fluid h-100 pt-4 pb-4\">\n            <div class=\"row h-100\">\n                <div class=\"col-12 d-flex align-items-end\">\n                    <div class=\"hero-content\">\n                        \n                        \n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n<script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    \/\/ Vimeo can run immediately since the SDK loads synchronously enough\n    const heroVideos = document.querySelectorAll('.hero-video-wrapper iframe');\n    heroVideos.forEach(iframe => {\n        if (iframe.src.includes('vimeo.com')) {\n            const player = new Vimeo.Player(iframe);\n            player.getDuration().then(duration => {\n                player.on('timeupdate', data => {\n                    if (data.seconds >= duration - 1) {\n                        player.setCurrentTime(0).then(() => player.play());\n                    }\n                });\n            });\n        }\n    });\n\n    \/\/ Collect YouTube iframes to initialize once the API is ready\n    window._ytHeroIframes = document.querySelectorAll('.hero-video-wrapper iframe[src*=\"youtube.com\"]');\n});\n\n\/\/ This is called automatically by the YouTube API once it's fully loaded\nwindow.onYouTubeIframeAPIReady = function() {\n    if (!window._ytHeroIframes) return;\n\n    window._ytHeroIframes.forEach(iframe => {\n        const videoId = iframe.src.match(\/embed\\\/([^?&]+)\/)[1];\n        const parent = iframe.parentNode;\n        iframe.remove();\n\n        const ytDiv = document.createElement('div');\n        ytDiv.id = 'yt-hero-' + Math.floor(Math.random() * 10000);\n        ytDiv.classList.add('hero-video');\n        parent.appendChild(ytDiv);\n\n        new YT.Player(ytDiv.id, {\n            videoId: videoId,\n            playerVars: {\n                autoplay: 1,\n                controls: 0,\n                loop: 1,\n                playlist: videoId,\n                mute: 1,\n                modestbranding: 1,\n                disablekb: 1,\n                playsinline: 1\n            },\n            events: {\n                onReady: function(event) {\n                    const duration = event.target.getDuration();\n                    setInterval(() => {\n                        const current = event.target.getCurrentTime();\n                        if (current >= duration - 1) {\n                            event.target.seekTo(0);\n                            event.target.playVideo();\n                        }\n                    }, 800);\n                }\n            }\n        });\n    });\n};\n<\/script>\n<section id=\"section-text-block_0e46eea9233a8f2b059580d27e1fa6c0\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Il coronavirus (Covid-19) ha fatto calare del 50% il fatturato della carta per fotocopie PaperWise presso i nostri clienti attuali! \u00c8 logico, dato che la carta per fotocopie ecosostenibile PaperWise viene fornita principalmente ad aziende i cui dipendenti hanno iniziato a lavorare da casa. Tuttavia, questo calo del fatturato porta anche benefici ambientali e una maggiore domanda di sostenibilit\u00e0!  <\/p>\n<p>Abbiamo approfondito la questione e confrontato alcuni dati con l&#8217;anno scorso. Dalla fondazione nel 2015, forniamo a oltre 100 clienti in patria e all&#8217;estero la carta sostenibile PaperWise <a href=\"https:\/\/paperwise.eu\/shop\/?_sfm_artikelen=kopieerpapier%20voor%20kantoor\">per fotocopie e stampa<\/a>. In questo confronto non includiamo i grossisti che vendono la nostra carta ecologica. Risultato: il fatturato della carta per fotocopie PaperWise si \u00e8 mediamente dimezzato presso i clienti esistenti a causa delle misure per il coronavirus. \u00c8 spiegabile: molti dipendenti lavorano da casa e non portano con s\u00e9 la carta dall&#8217;ufficio. Anzi, ci chiediamo se il coronavirus non abbia dato la spinta finale verso un <a href=\"https:\/\/paperwise.eu\/verminder-papiergebruik\/\">ufficio senza carta<\/a>. Anche se, dal nostro punto di vista, sarebbe un bel gesto di attenzione verso i dipendenti se venisse data loro la possibilit\u00e0 di portare a casa la carta per stampare dall&#8217;ufficio.      <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-printing-paperless-office.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_9106cca667be296a7e9c51eb0560bdd2\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Fino al 2010, il mercato dei tipi di carta grafica in Europa era ancora in crescita. Si pensi alla carta per libri, riviste, brochure, carta intestata, buste, ma anche carta per fotocopie e stampa (Fonte: CEPI Key Statistics). Dal 2010 vediamo il mercato europeo della carta grafica contrarsi rapidamente. Nel 2019, il mercato si \u00e8 ridotto del 40% rispetto al 2010. La causa principale \u00e8 la digitalizzazione. Leggiamo le notizie in digitale. Le brochure sono state sostituite dai siti web. Fatture e volantini vengono inviati via e-mail e le abitudini di stampa e fotocopia cambiano. Su base annua, si tratta di una contrazione di quasi il 4,5% all&#8217;anno. Quindi, un calo del 50% del fatturato della carta per fotocopie e stampa (presso i clienti esistenti) in pochi mesi \u00e8 un dato enorme.         <\/p>\n<p>Guardiamo il lato positivo, perch\u00e9 in PaperWise crediamo nella forza del pensiero positivo. Fin dal primo giorno riportiamo sul fronte della confezione della carta sostenibile PaperWise: \u201cLa natura non conosce rifiuti. Insieme trasformiamo i rifiuti in carta bellissima. Se possibile, usa meno carta. Se usi la carta, scegli PaperWise\u201d. Noi di PaperWise siamo quindi felici che il coronavirus abbia un effetto positivo in questo ambito e faccia calare drasticamente il consumo di carta. Questo contribuisce alla <a href=\"https:\/\/paperwise.eu\/visie-missie\/\">nostra missione<\/a> di rendere il mondo un po&#8217; pi\u00f9 bello. Anche se PaperWise \u00e8 la carta per fotocopie e stampa pi\u00f9 sostenibile, non usare qualcosa \u00e8 sempre meglio!     <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-eco-friendly-sustainable-copy-printing-paper-agriwaste-plantbased-office.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_452fe3fba9f6843376bf34133b862bdc\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Nonostante il calo del fatturato della carta per fotocopie e stampa PaperWise (presso i clienti esistenti) dovuto alla crisi del coronavirus, vediamo che il mercato ha abbracciato pienamente la sostenibilit\u00e0. Sempre pi\u00f9 persone e aziende si rendono conto che la sostenibilit\u00e0 non \u00e8 pi\u00f9 una moda, ma la nuova normalit\u00e0. La richiesta di informazioni e campioni per imballaggi e stampati sostenibili non \u00e8 mai stata cos\u00ec alta. PaperWise continua a crescere con forza anche nel 2020. Alla fine del terzo trimestre del 2020, abbiamo potuto aiutare il 35% di clienti in pi\u00f9 rispetto all&#8217;anno precedente a realizzare i propri <a href=\"https:\/\/paperwise.eu\/it\/\">obiettivi di sostenibilit\u00e0<\/a>. Ne siamo super orgogliosi e molto felici. Contribuiamo insieme positivamente a un mondo migliore!      <\/p>\n<p>Anche tu hai la curiosit\u00e0 di sapere come puoi contribuire positivamente a un mondo migliore scegliendo la carta e il cartone PaperWise? Vuoi sapere come i residui dell&#8217;agricoltura diventano materie prime per carta di alta qualit\u00e0? Sei aperto a dare forma, insieme, a un&#8217;economia circolare? Vuoi mettere a disposizione la carta per fotocopie per i tuoi dipendenti a casa? Contattaci senza impegno o richiedici un pacchetto di campioni con tutti i tipi di carta PaperWise. Saremo felici di aiutarti.     <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":16488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[361],"tags":[364],"class_list":["post-16487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-organizzazione"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?<\/title>\n<meta name=\"description\" content=\"L&#039;impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?\" \/>\n<meta property=\"og:description\" content=\"L&#039;impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-30T05:02:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T04:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"romano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/\"},\"author\":{\"name\":\"romano\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"headline\":\"Il coronavirus causa un calo del fatturato, ma anche benefici per l&#8217;ambiente\",\"datePublished\":\"2025-11-30T05:02:54+00:00\",\"dateModified\":\"2026-05-20T04:11:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg\",\"keywords\":[\"Organizzazione\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/\",\"name\":\"Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg\",\"datePublished\":\"2025-11-30T05:02:54+00:00\",\"dateModified\":\"2026-05-20T04:11:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"description\":\"L'impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg\",\"contentUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg\",\"width\":1920,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il coronavirus causa un calo del fatturato, ma anche benefici per l&#8217;ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\",\"name\":\"romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"caption\":\"romano\"},\"url\":\"https:\\\/\\\/paperwise.eu\\\/it\\\/author\\\/romano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?","description":"L'impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/","og_locale":"it_IT","og_type":"article","og_title":"Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?","og_description":"L'impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?","og_url":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/","og_site_name":"Paperwise","article_published_time":"2025-11-30T05:02:54+00:00","article_modified_time":"2026-05-20T04:11:38+00:00","og_image":[{"width":1920,"height":786,"url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg","type":"image\/jpeg"}],"author":"romano","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"romano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#article","isPartOf":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/"},"author":{"name":"romano","@id":"https:\/\/paperwise.eu\/it\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"headline":"Il coronavirus causa un calo del fatturato, ma anche benefici per l&#8217;ambiente","datePublished":"2025-11-30T05:02:54+00:00","dateModified":"2026-05-20T04:11:38+00:00","mainEntityOfPage":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/"},"wordCount":13,"image":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg","keywords":["Organizzazione"],"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/","url":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/","name":"Riduzione del consumo di carta e ufficio senza carta grazie al coronavirus?","isPartOf":{"@id":"https:\/\/paperwise.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#primaryimage"},"image":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg","datePublished":"2025-11-30T05:02:54+00:00","dateModified":"2026-05-20T04:11:38+00:00","author":{"@id":"https:\/\/paperwise.eu\/it\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"description":"L'impatto del coronavirus sul consumo di carta per stampa e fotocopie negli uffici. Covid: la spinta finale verso un ufficio senza carta?","breadcrumb":{"@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#primaryimage","url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg","contentUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-environmental-benefit-eco-friendly-copy-paper-corona-covid-paperless-office.jpg","width":1920,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/it\/il-coronavirus-causa-un-calo-del-fatturato-ma-anche-benefici-per-lambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paperwise.eu\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"Il coronavirus causa un calo del fatturato, ma anche benefici per l&#8217;ambiente"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/it\/#website","url":"https:\/\/paperwise.eu\/it\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/paperwise.eu\/it\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e","name":"romano","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","caption":"romano"},"url":"https:\/\/paperwise.eu\/it\/author\/romano\/"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/posts\/16487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/comments?post=16487"}],"version-history":[{"count":1,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/posts\/16487\/revisions"}],"predecessor-version":[{"id":16491,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/posts\/16487\/revisions\/16491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/media\/16488"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/media?parent=16487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/categories?post=16487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paperwise.eu\/it\/wp-json\/wp\/v2\/tags?post=16487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}