{"id":18555,"date":"2025-12-05T08:31:31","date_gmt":"2025-12-05T07:31:31","guid":{"rendered":"https:\/\/paperwise.eu\/toepassingen\/emballages-pour-noix\/"},"modified":"2025-12-05T08:31:31","modified_gmt":"2025-12-05T07:31:31","slug":"emballages-pour-noix","status":"publish","type":"toepassing_pt","link":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/","title":{"rendered":"Emballages pour noix"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","toepassing_cat_tax":[402,403],"class_list":["post-18555","toepassing_pt","type-toepassing_pt","status-publish","hentry","toepassing_cat_tax-emballages-durables","toepassing_cat_tax-manger-boire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emballages durables pour noix | \u00c9cologiques et qualitatifs<\/title>\n<meta name=\"description\" content=\"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emballages durables pour noix | \u00c9cologiques et qualitatifs\" \/>\n<meta property=\"og:description\" content=\"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pour-noix\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pour-noix\\\/\",\"name\":\"Emballages durables pour noix | \u00c9cologiques et qualitatifs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\"},\"datePublished\":\"2025-12-05T07:31:31+00:00\",\"description\":\"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pour-noix\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pour-noix\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pour-noix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emballages pour noix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emballages durables pour noix | \u00c9cologiques et qualitatifs","description":"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/","og_locale":"fr_FR","og_type":"article","og_title":"Emballages durables pour noix | \u00c9cologiques et qualitatifs","og_description":"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.","og_url":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/","og_site_name":"Paperwise","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/","url":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/","name":"Emballages durables pour noix | \u00c9cologiques et qualitatifs","isPartOf":{"@id":"https:\/\/paperwise.eu\/fr\/#website"},"datePublished":"2025-12-05T07:31:31+00:00","description":"R\u00e9duisez l\u2019empreinte \u00e9cologique avec les emballages durables pour noix PaperWise. Qualitatifs, respectueux de l\u2019environnement et socialement responsables.","breadcrumb":{"@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pour-noix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/paperwise.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Emballages pour noix"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/fr\/#website","url":"https:\/\/paperwise.eu\/fr\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_pt\/18555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_pt"}],"about":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/types\/toepassing_pt"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/media?parent=18555"}],"wp:term":[{"taxonomy":"toepassing_cat_tax","embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_cat_tax?post=18555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}