{"id":18504,"date":"2025-12-05T08:30:43","date_gmt":"2025-12-05T07:30:43","guid":{"rendered":"https:\/\/paperwise.eu\/toepassingen\/emballages-pouch\/"},"modified":"2025-12-05T08:30:43","modified_gmt":"2025-12-05T07:30:43","slug":"emballages-pouch","status":"publish","type":"toepassing_pt","link":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/","title":{"rendered":"Emballages pouch"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","toepassing_cat_tax":[402,404],"class_list":["post-18504","toepassing_pt","type-toepassing_pt","status-publish","hentry","toepassing_cat_tax-emballages-durables","toepassing_cat_tax-produits-de-soin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emballages pouch durables | \u00c9cologiques et qualitatifs<\/title>\n<meta name=\"description\" content=\"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emballages pouch durables | \u00c9cologiques et qualitatifs\" \/>\n<meta property=\"og:description\" content=\"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pouch\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pouch\\\/\",\"name\":\"Emballages pouch durables | \u00c9cologiques et qualitatifs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\"},\"datePublished\":\"2025-12-05T07:30:43+00:00\",\"description\":\"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pouch\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pouch\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/toepassingen\\\/emballages-pouch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emballages pouch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emballages pouch durables | \u00c9cologiques et qualitatifs","description":"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/","og_locale":"fr_FR","og_type":"article","og_title":"Emballages pouch durables | \u00c9cologiques et qualitatifs","og_description":"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.","og_url":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/","og_site_name":"Paperwise","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/","url":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/","name":"Emballages pouch durables | \u00c9cologiques et qualitatifs","isPartOf":{"@id":"https:\/\/paperwise.eu\/fr\/#website"},"datePublished":"2025-12-05T07:30:43+00:00","description":"R\u00e9duisez votre empreinte \u00e9cologique avec les emballages pouch PaperWise. Qualit\u00e9, respect de l\u2019environnement et responsabilit\u00e9 sociale.","breadcrumb":{"@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/fr\/toepassingen\/emballages-pouch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/paperwise.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Emballages pouch"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/fr\/#website","url":"https:\/\/paperwise.eu\/fr\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_pt\/18504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_pt"}],"about":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/types\/toepassing_pt"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/media?parent=18504"}],"wp:term":[{"taxonomy":"toepassing_cat_tax","embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/toepassing_cat_tax?post=18504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}