{"id":18381,"date":"2025-11-27T06:40:50","date_gmt":"2025-11-27T05:40:50","guid":{"rendered":"https:\/\/paperwise.eu\/paperwise-fierement-certifie-pour-le-recyclage\/"},"modified":"2026-07-03T07:32:13","modified_gmt":"2026-07-03T05:32:13","slug":"paperwise-fierement-certifie-pour-le-recyclage","status":"publish","type":"post","link":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/","title":{"rendered":"PaperWise fi\u00e8rement certifi\u00e9 pour le recyclage"},"content":{"rendered":"\n<section class=\"section-hero-paperwise text-color-light\" >\n    <div class=\"hero-background \" style=\"background-image: url('https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg');\">\n\n        \n        <div class=\"container-fluid h-100 pt-4 pb-4\">\n            <div class=\"row h-100\">\n                <div class=\"col-12 d-flex align-items-end\">\n                    <div class=\"hero-content\">\n                                                    <h1 class=\"hero-title\">\n                                <span class=\"hero-title-highlight\">PaperWise fi\u00e8rement certifi\u00e9<\/span> pour le recyclage                            <\/h1>\n                        \n                        \n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n<script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    \/\/ Vimeo can run immediately since the SDK loads synchronously enough\n    const heroVideos = document.querySelectorAll('.hero-video-wrapper iframe');\n    heroVideos.forEach(iframe => {\n        if (iframe.src.includes('vimeo.com')) {\n            const player = new Vimeo.Player(iframe);\n            player.getDuration().then(duration => {\n                player.on('timeupdate', data => {\n                    if (data.seconds >= duration - 1) {\n                        player.setCurrentTime(0).then(() => player.play());\n                    }\n                });\n            });\n        }\n    });\n\n    \/\/ Collect YouTube iframes to initialize once the API is ready\n    window._ytHeroIframes = document.querySelectorAll('.hero-video-wrapper iframe[src*=\"youtube.com\"]');\n});\n\n\/\/ This is called automatically by the YouTube API once it's fully loaded\nwindow.onYouTubeIframeAPIReady = function() {\n    if (!window._ytHeroIframes) return;\n\n    window._ytHeroIframes.forEach(iframe => {\n        const videoId = iframe.src.match(\/embed\\\/([^?&]+)\/)[1];\n        const parent = iframe.parentNode;\n        iframe.remove();\n\n        const ytDiv = document.createElement('div');\n        ytDiv.id = 'yt-hero-' + Math.floor(Math.random() * 10000);\n        ytDiv.classList.add('hero-video');\n        parent.appendChild(ytDiv);\n\n        new YT.Player(ytDiv.id, {\n            videoId: videoId,\n            playerVars: {\n                autoplay: 1,\n                controls: 0,\n                loop: 1,\n                playlist: videoId,\n                mute: 1,\n                modestbranding: 1,\n                disablekb: 1,\n                playsinline: 1\n            },\n            events: {\n                onReady: function(event) {\n                    const duration = event.target.getDuration();\n                    setInterval(() => {\n                        const current = event.target.getCurrentTime();\n                        if (current >= duration - 1) {\n                            event.target.seekTo(0);\n                            event.target.playVideo();\n                        }\n                    }, 800);\n                }\n            }\n        });\n    });\n};\n<\/script>\n<section id=\"section-text-block_e7758dcfc34fd99aec47c3bcc2da25e6\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Nous sommes fiers d\u2019annoncer que PaperWise est officiellement certifi\u00e9 pour le recyclage du papier selon la norme stricte de la CEPI, la \u00ab CEPI\u2019s Recyclability Laboratory Test Method (Version 2) \u00bb. C\u2019est une \u00e9tape majeure pour nous, sur laquelle nous souhaitons vous en dire plus et vous expliquer pourquoi elle est importante pour vous. \u00c0 une \u00e9poque o\u00f9 la durabilit\u00e9 et la conscience environnementale deviennent de plus en plus essentielles, la demande de produits et de mat\u00e9riaux recyclables a augment\u00e9 de mani\u00e8re exponentielle. Le papier, l\u2019un des objets du quotidien les plus courants, joue un r\u00f4le crucial dans cette transition vers une \u00e9conomie circulaire.  <\/p>\n<p>Nous sommes fiers d\u2019annoncer que PaperWise est officiellement certifi\u00e9 pour le recyclage du papier selon la norme stricte de la CEPI, la \u00ab CEPI\u2019s Recyclability Laboratory Test Method (Version 2) \u00bb. C\u2019est une \u00e9tape majeure pour nous, sur laquelle nous souhaitons vous en dire plus et vous expliquer pourquoi elle est importante pour vous. \u00c0 une \u00e9poque o\u00f9 la durabilit\u00e9 et la conscience environnementale deviennent de plus en plus essentielles, la demande de produits et de mat\u00e9riaux recyclables a augment\u00e9 de mani\u00e8re exponentielle. Le papier, l\u2019un des objets du quotidien les plus courants, joue un r\u00f4le crucial dans cette transition vers une \u00e9conomie circulaire.  <\/p>\n<h2>L\u2019importance du recyclage du papier<\/h2>\n<p>Le recyclage du papier ne signifie pas seulement la r\u00e9utilisation de vieux papiers, mais aussi la r\u00e9duction de la pression sur les ressources naturelles. En recyclant le papier, on \u00e9vite l\u2019abattage d\u2019arbres, on \u00e9conomise de l\u2019\u00e9nergie et on r\u00e9duit les \u00e9missions de gaz \u00e0 effet de serre. Cela s\u2019inscrit parfaitement dans le cadre plus large de l\u2019\u00e9conomie circulaire, o\u00f9 les mati\u00e8res premi\u00e8res sont utilis\u00e9es et r\u00e9utilis\u00e9es dans un cycle continu, r\u00e9duisant ainsi consid\u00e9rablement l\u2019impact environnemental.  <\/p>\n<h2>PaperWise : durabilit\u00e9 et qualit\u00e9 main dans la main<\/h2>\n<p>Ce qui distingue PaperWise, ce n\u2019est pas seulement l\u2019utilisation de mati\u00e8res premi\u00e8res secondaires (d\u00e9chets agricoles), mais aussi la qualit\u00e9 in\u00e9gal\u00e9e du papier et du carton. PaperWise est unique par l\u2019accent mis \u00e0 la fois sur la qualit\u00e9 et la durabilit\u00e9. Nous sommes donc extr\u00eamement fiers d\u2019annoncer que tous les types de papier PaperWise ont pass\u00e9 avec brio le processus de certification pour le recyclage du papier. C\u2019est la preuve que les clients n\u2019ont pas \u00e0 faire de compromis sur la qualit\u00e9 lorsqu\u2019ils choisissent le papier le plus durable pour leurs emballages, leurs impressions et leurs applications de bureau.   <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-moyen parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_images_900-x-450.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_9e60956a55d0102b736d2aa87a8381f4\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>Recyclage avec PaperWise<\/h2>\n<p>L\u2019une des caract\u00e9ristiques fortes de PaperWise est qu\u2019il peut \u00eatre recycl\u00e9 sans probl\u00e8me avec d\u2019autres types de papier. Cela contribue \u00e0 une utilisation plus efficace des mati\u00e8res premi\u00e8res et favorise un syst\u00e8me en boucle ferm\u00e9e. Cela confirme une fois de plus que la cellulose issue des d\u00e9chets agricoles est une excellente mati\u00e8re premi\u00e8re vierge pour la production de papier et de carton de haute qualit\u00e9. La fibre de cellulose de PaperWise provient directement de la plante, n\u2019a pas encore \u00e9t\u00e9 recycl\u00e9e et constitue pr\u00e9cis\u00e9ment pour cette raison une am\u00e9lioration de la qualit\u00e9 pour le <a href=\"https:\/\/paperwise.eu\/gerecycled-papier\/\">papier recycl\u00e9<\/a>.   <\/p>\n<h2>Certification par PTS selon la m\u00e9thode CEPI\u2019s Recyclability Laboratory Test Method<\/h2>\n<p>La certification de PaperWise pour le recyclage a \u00e9t\u00e9 r\u00e9alis\u00e9e avec soin par PTS en Allemagne. PTS, Papiertechnische Stiftung, est reconnue pour ses \u00e9valuations approfondies du papier et du carton \u00e0 des fins de recyclage. Nous sommes fiers de notre collaboration avec PTS, qui nous a aid\u00e9s \u00e0 d\u00e9montrer que le papier PaperWise r\u00e9pond aux normes les plus \u00e9lev\u00e9es en mati\u00e8re de recyclage du papier. La certification a \u00e9t\u00e9 effectu\u00e9e selon la norme \u00ab CEPI\u2019s Recyclability Laboratory Test Method (Version 2) \u00bb.   <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-moyen parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_images_900-x-4502.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_00c6a14de8141834eb31caf1b58952a0\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Norme \u00ab CEPI\u2019s Recyclability Laboratory Test Method (Version 2) \u00bb.<br \/>\nCette m\u00e9thode, d\u00e9velopp\u00e9e par la Conf\u00e9d\u00e9ration des Industries Papeti\u00e8res Europ\u00e9ennes (CEPI), offre un aper\u00e7u approfondi de la recyclabilit\u00e9 du papier. Un \u00ab score de recyclabilit\u00e9 \u00bb est attribu\u00e9 aux types de papier test\u00e9s, rendant ainsi les performances en mati\u00e8re de recyclage transparentes. <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-moyen parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_images_900-x-4503.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_90b616c5459756fc9df4e53e34eed108\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>Contactez-nous<\/h2>\n<p>Si vous souhaitez en savoir plus sur PaperWise, si vous avez des questions ou si vous souhaitez recevoir des \u00e9chantillons, n\u2019h\u00e9sitez pas \u00e0 nous contacter. Vous pouvez envoyer un e-mail \u00e0 <a href=\"mailto:info@paperwise.eu\">info@paperwise.eu<\/a> ou nous contacter par t\u00e9l\u00e9phone au +31 492 849 575. <\/p>\n<p>Chez PaperWise, nous sommes enthousiastes quant \u00e0 l\u2019avenir de la durabilit\u00e9 et nous nous r\u00e9jouissons de contribuer avec vous \u00e0 un monde o\u00f9 l\u2019utilisation responsable des mat\u00e9riaux est la norme. Outre la certification pour le recyclage, PaperWise est \u00e9galement <a href=\"https:\/\/paperwise.eu\/keurmerken-2\/\">certifi\u00e9<\/a> pour la s\u00e9curit\u00e9 alimentaire (EC1935\/2004), le compostage industriel (EN13432) et le compostage domestique (DIN CERTCO HOME COMPOSTABLE). <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":18383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[405],"tags":[407],"class_list":["post-18381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-certifications"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9<\/title>\n<meta name=\"description\" content=\"PaperWise m\u00e8ne la danse en mati\u00e8re d&#039;utilisation de papier respectueux de l&#039;environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9\" \/>\n<meta property=\"og:description\" content=\"PaperWise m\u00e8ne la danse en mati\u00e8re d&#039;utilisation de papier respectueux de l&#039;environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-27T05:40:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T05:32:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"romano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/\"},\"author\":{\"name\":\"romano\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"headline\":\"PaperWise fi\u00e8rement certifi\u00e9 pour le recyclage\",\"datePublished\":\"2025-11-27T05:40:50+00:00\",\"dateModified\":\"2026-07-03T05:32:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/\"},\"wordCount\":7,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/recycled-papier-certificeert_header_1100-x-450.jpeg\",\"keywords\":[\"Certifications\"],\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/\",\"name\":\"Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/recycled-papier-certificeert_header_1100-x-450.jpeg\",\"datePublished\":\"2025-11-27T05:40:50+00:00\",\"dateModified\":\"2026-07-03T05:32:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"description\":\"PaperWise m\u00e8ne la danse en mati\u00e8re d'utilisation de papier respectueux de l'environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/recycled-papier-certificeert_header_1100-x-450.jpeg\",\"contentUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/recycled-papier-certificeert_header_1100-x-450.jpeg\",\"width\":1920,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/paperwise-fierement-certifie-pour-le-recyclage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PaperWise fi\u00e8rement certifi\u00e9 pour le recyclage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\",\"name\":\"romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"caption\":\"romano\"},\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/author\\\/romano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9","description":"PaperWise m\u00e8ne la danse en mati\u00e8re d'utilisation de papier respectueux de l'environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/","og_locale":"fr_FR","og_type":"article","og_title":"Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9","og_description":"PaperWise m\u00e8ne la danse en mati\u00e8re d'utilisation de papier respectueux de l'environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.","og_url":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/","og_site_name":"Paperwise","article_published_time":"2025-11-27T05:40:50+00:00","article_modified_time":"2026-07-03T05:32:13+00:00","og_image":[{"width":1920,"height":786,"url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg","type":"image\/jpeg"}],"author":"romano","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"romano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#article","isPartOf":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/"},"author":{"name":"romano","@id":"https:\/\/paperwise.eu\/fr\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"headline":"PaperWise fi\u00e8rement certifi\u00e9 pour le recyclage","datePublished":"2025-11-27T05:40:50+00:00","dateModified":"2026-07-03T05:32:13+00:00","mainEntityOfPage":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/"},"wordCount":7,"commentCount":0,"image":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg","keywords":["Certifications"],"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/","url":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/","name":"Certification CEPI pour le recyclage du papier : un papier durable et de qualit\u00e9","isPartOf":{"@id":"https:\/\/paperwise.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#primaryimage"},"image":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg","datePublished":"2025-11-27T05:40:50+00:00","dateModified":"2026-07-03T05:32:13+00:00","author":{"@id":"https:\/\/paperwise.eu\/fr\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"description":"PaperWise m\u00e8ne la danse en mati\u00e8re d'utilisation de papier respectueux de l'environnement gr\u00e2ce \u00e0 la certification CEPI. Choisissez un papier durable et de qualit\u00e9.","breadcrumb":{"@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#primaryimage","url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg","contentUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/recycled-papier-certificeert_header_1100-x-450.jpeg","width":1920,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/fr\/paperwise-fierement-certifie-pour-le-recyclage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/paperwise.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"PaperWise fi\u00e8rement certifi\u00e9 pour le recyclage"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/fr\/#website","url":"https:\/\/paperwise.eu\/fr\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/paperwise.eu\/fr\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e","name":"romano","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","caption":"romano"},"url":"https:\/\/paperwise.eu\/fr\/author\/romano\/"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/posts\/18381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/comments?post=18381"}],"version-history":[{"count":1,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/posts\/18381\/revisions"}],"predecessor-version":[{"id":18386,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/posts\/18381\/revisions\/18386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/media\/18383"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/media?parent=18381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/categories?post=18381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/tags?post=18381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}