{"id":18997,"date":"2025-11-14T15:48:49","date_gmt":"2025-11-14T14:48:49","guid":{"rendered":"https:\/\/paperwise.eu\/avantages\/"},"modified":"2026-07-08T14:17:50","modified_gmt":"2026-07-08T12:17:50","slug":"avantages","status":"publish","type":"page","link":"https:\/\/paperwise.eu\/fr\/avantages\/","title":{"rendered":"Avantages"},"content":{"rendered":"\n<section class=\"section-hero-paperwise text-color-light\" >\n    <div class=\"hero-background has-video\" >\n\n                    <!-- YouTube Video Background -->\n            <div class=\"hero-video-wrapper\">\n                <iframe\n                    class=\"hero-video\"\n                    src=\"https:\/\/www.youtube.com\/embed\/twiTZPIhOTI?autoplay=1&mute=1&loop=1&playlist=twiTZPIhOTI&controls=0&showinfo=0&rel=0&modestbranding=1&iv_load_policy=3&disablekb=1&playsinline=1\"\n                    frameborder=\"0\"\n                    allow=\"autoplay; encrypted-media\"\n                    allowfullscreen\n                    playsinline\n                    loading=\"lazy\">\n                <\/iframe>\n            <\/div>\n\n                    \n        <div class=\"container-fluid h-100 pt-4 pb-4\">\n            <div class=\"row h-100\">\n                <div class=\"col-12 d-flex align-items-end\">\n                    <div class=\"hero-content\">\n                                                    <h1 class=\"hero-title\">\n                                <span class=\"hero-title-highlight\">Papier \u00e0 base<\/span> de d\u00e9chets agricoles                            <\/h1>\n                        \n                                                    <div class=\"hero-description\">\n                                Le type de papier le plus durable. Pour tous ceux qui<br \/>\r\nsouhaitent contribuer \u00e0 un monde meilleur et \u00e0 une<br \/>\r\n\u00e9conomie circulaire.  Adieu les arbres, bonjour les r\u00e9sidus v\u00e9g\u00e9taux !                            <\/div>\n                        \n                                                    <div class=\"hero-cta\">\n                                                                <a href=\"https:\/\/paperwise.eu\/fr\/boutique-en-ligne\/\"\n                                    target=\"\"\n                                    class=\"btn-primary-paperwise cta-left-btn\">\n                                    <span>Assortiment<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\" \/>\n                                    <\/svg>\n                                <\/a>\n                                \n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n<script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    \/\/ Vimeo can run immediately since the SDK loads synchronously enough\n    const heroVideos = document.querySelectorAll('.hero-video-wrapper iframe');\n    heroVideos.forEach(iframe => {\n        if (iframe.src.includes('vimeo.com')) {\n            const player = new Vimeo.Player(iframe);\n            player.getDuration().then(duration => {\n                player.on('timeupdate', data => {\n                    if (data.seconds >= duration - 1) {\n                        player.setCurrentTime(0).then(() => player.play());\n                    }\n                });\n            });\n        }\n    });\n\n    \/\/ Collect YouTube iframes to initialize once the API is ready\n    window._ytHeroIframes = document.querySelectorAll('.hero-video-wrapper iframe[src*=\"youtube.com\"]');\n});\n\n\/\/ This is called automatically by the YouTube API once it's fully loaded\nwindow.onYouTubeIframeAPIReady = function() {\n    if (!window._ytHeroIframes) return;\n\n    window._ytHeroIframes.forEach(iframe => {\n        const videoId = iframe.src.match(\/embed\\\/([^?&]+)\/)[1];\n        const parent = iframe.parentNode;\n        iframe.remove();\n\n        const ytDiv = document.createElement('div');\n        ytDiv.id = 'yt-hero-' + Math.floor(Math.random() * 10000);\n        ytDiv.classList.add('hero-video');\n        parent.appendChild(ytDiv);\n\n        new YT.Player(ytDiv.id, {\n            videoId: videoId,\n            playerVars: {\n                autoplay: 1,\n                controls: 0,\n                loop: 1,\n                playlist: videoId,\n                mute: 1,\n                modestbranding: 1,\n                disablekb: 1,\n                playsinline: 1\n            },\n            events: {\n                onReady: function(event) {\n                    const duration = event.target.getDuration();\n                    setInterval(() => {\n                        const current = event.target.getCurrentTime();\n                        if (current >= duration - 1) {\n                            event.target.seekTo(0);\n                            event.target.playVideo();\n                        }\n                    }, 800);\n                }\n            }\n        });\n    });\n};\n<\/script>\n<section class=\"section-two-images-info-usps section-two-images-info-usps\" >\n    <div class=\"container pt-5 pb-5\">\n        <div class=\"row align-items-start\">\n            <!-- Left: Two Images (50%) -->\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"images-wrapper\">\n                                            <div class=\"image-left\">\n                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/b66d703cf3c7934f472aaf6132d3deb7ddb2b5f8-scaled.jpg\"\n                                alt=\"\"\n                                class=\"img-fluid\">\n                        <\/div>\n                    \n                                            <div class=\"image-right\">\n                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/a60f804f82b0628f6991c60df1fac5d71607a626-scaled.jpg\"\n                                alt=\"\"\n                                class=\"img-fluid\">\n                        <\/div>\n                                    <\/div>\n            <\/div>\n\n            <!-- Right: Info & USPs (50%) -->\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"info-wrapper\">\n                                            <h2 class=\"section-title\">\n                                                            <span class=\"title-highlight\">Durabilit\u00e9<\/span>\n                                                        pour tous                        <\/h2>\n                    \n                                            <div class=\"section-description\">\n                            PaperWise, c\u2019est du papier et du carton fabriqu\u00e9s \u00e0 partir de r\u00e9sidus v\u00e9g\u00e9taux. Votre papier durable pour les emballages, l\u2019impression et le papier de copie. 47 % plus respectueux de l\u2019environnement. Contribuez vous aussi \u00e0 un monde meilleur.                           <\/div>\n                    \n                                            <div class=\"usps-grid\">\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/014a345025fd91a07348f337c954aba418f0cff5.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Mati\u00e8re premi\u00e8re secondaire<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/Scherm\u00adafbeelding-2025-11-04-om-11.42.51.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">S\u00e9curit\u00e9 alimentaire<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/089125452d1aeb86438cf14e7f6bc708cf329d73.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Circulaire<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/a34ef04a35f06a2bc5a0cc8a6a1a5080a23c0d88.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Recyclable<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/68d30017a2502decc075c88436ae2f948e84022d.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Respectueux des arbres<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/ff69835053943c9e16cf55ea603f32ad037f2e9b.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Compostable \u00e0 domicile<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/Asset-4.svg\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">\u00c9conomie de CO\u2082<\/div>\n                                                                    <\/div>\n                                                            <div class=\"usp-item\">\n                                                                            <div class=\"usp-icon\">\n                                            <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/Schermafbeelding-2025-11-17-om-13.14.15.png\"\n                                                alt=\"\">\n                                        <\/div>\n                                                                                                                <div class=\"usp-text\">Compostable industriellement<\/div>\n                                                                    <\/div>\n                                                    <\/div>\n                    \n                                            <div class=\"cta-buttons\">\n                                                            <a href=\"https:\/\/paperwise.eu\/fr\/pour-qui\/\"\n                                    target=\"_blank\"\n                                    class=\"btn-primary-paperwise\">\n                                    <span>Pour qui<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\" \/>\n                                    <\/svg>\n                                <\/a>\n                            \n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"section-process-visual pt-4 pb-4 section-process-visual\" >\n    <div class=\"container-fluid pt-4 pb-4\">\n        <!-- Title -->\n                    <h2 class=\"section-title\">\n                                    <span class=\"title-line-1\">Des d\u00e9chets agricoles  <\/span>\n                                                    <span class=\"title-line-2\">au papier<\/span>\n                            <\/h2>\n        \n        <div class=\"process-content-wrapper\">\n            <div class=\"row align-items-start\">\n                <!-- Left Column: Text Content -->\n                <div class=\"col-lg-5\">\n                    <div class=\"text-content\">\n                                                    <p class=\"intro-text\">PaperWise valorise les d\u00e9chets agricoles, une mati\u00e8re premi\u00e8re secondaire disponible chaque ann\u00e9e. On en extrait la cellulose, l\u2019ingr\u00e9dient de base du papier qui, dans l\u2019industrie papeti\u00e8re traditionnelle, provient des arbres. En extrayant la cellulose des r\u00e9sidus v\u00e9g\u00e9taux, les arbres peuvent \u00eatre pr\u00e9serv\u00e9s.  <\/p>\n                        \n                                                    <div class=\"info-box\">\n                                                                    <h3 class=\"box-title\">Cultures<\/h3>\n                                                                                                    <p class=\"box-text\">La culture de plantes telles que le riz, le bl\u00e9, l\u2019orge, l\u2019avoine et la canne \u00e0 sucre constitue, depuis des mill\u00e9naires, l\u2019un des principaux moyens de subsistance de l\u2019humanit\u00e9. <\/p>\n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n\n                <!-- Right Column: Visual Image -->\n                <div class=\"col-lg-7\">\n                    <div class=\"visual-wrapper\">\n                        <div \n                            class=\"infographic-item gewassen active\"\n                            data-title=\"Cultures\"\n                            data-text=\"Het verbouwen van gewassen, zoals rijst, tarwe, gerst, haver en suikerriet, is al duizenden jaren \u00e9\u00e9n van de belangrijkste manieren waarop mensen in hun voedsel voorzien.\"\n                        >\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/175002121_xl.jpg\"\/>   \n                                <span class=\"infographic-title\">Cultures<\/span>\n                        <\/div>\n                        <div \n                            class=\"infographic-item stengels\"\n                            data-title=\"Tiges\"\n                            data-text=\"80%  van een gewas blijft onbenut: de niet-eetbare stengels die overblijven na oogst en voedselverwerking. Ook wel landbouwafval genoemd.\"\n                        >\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/victoria-priessnitz-IPuuhSmsFIc-unsplash.jpg\"\/>   \n                                <span class=\"infographic-title\">Tiges<\/span>\n                        <\/div>\n                        <div \n                            class=\"infographic-item plantresten\"\n                            data-title=\"R\u00e9sidus v\u00e9g\u00e9taux\"\n                            data-text=\"Jaarlijks komen er miljarden tonnen landbouwafval beschikbaar. Zonde om dit als afval te zien! PaperWise geeft landbouwafval (plantresten) een tweede leven als grondstof voor papier.\"\n                        >\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/A.PaperWise-agri-waste-22.jpg\"\/>   \n                                <span class=\"infographic-title\">R\u00e9sidus v\u00e9g\u00e9taux<\/span>\n                        <\/div>\n                        <div \n                            class=\"infographic-item cellulose\"\n                            data-title=\"Cellulose\"\n                            data-text=\"Uit de vezels van de plantresten halen we cellulose; h\u00e9t basisingredi\u00ebnt voor het maken van papier\"\n                        >\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/cellulose-AI.jpg\"\/>   \n                                <span class=\"infographic-title\">Cellulose<\/span>\n                        <\/div>\n                        <div \n                            class=\"infographic-item paperwise\"\n                            data-title=\"Paperwise\"\n                            data-text=\"PaperWise is papier van landbouwafval. De meest duurzame papiersoort. Voor iedereen die wilt bijdragen aan betere wereld en circulaire economie\"\n                        >\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/PaperWise-range-White-Natural-Natural-Coated1sidewhite-2.jpg\"\/>   \n                                <span class=\"infographic-title\">Paperwise<\/span>\n                        <\/div>\n                        <div class=\"infographic-centre-title\">\n                                <span class=\"box-title\">wise<\/span>\n                                <span class=\"box-title title-line-2\">With Waste<\/span>\n                        <\/div>\n                        <div class=\"infographic-arrows-container\">\n                            <div class=\"infographic-arrow arrow-1\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/arrow.svg\"\/>   \n                            <\/div>\n                            <div class=\"infographic-arrow arrow-2\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/arrow.svg\"\/>   \n                            <\/div>\n                            <div class=\"infographic-arrow arrow-3\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/arrow.svg\"\/>   \n                            <\/div>\n                            <div class=\"infographic-arrow arrow-4\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/arrow.svg\"\/>   \n                            <\/div>\n                            <div class=\"infographic-arrow arrow-5\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/arrow-mirror.svg\"\/>   \n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script>\n    document.addEventListener('DOMContentLoaded', function () {\n        const items = document.querySelectorAll('.infographic-item');\n        const boxTitle = document.querySelector('.info-box .box-title');\n        const boxText = document.querySelector('.info-box .box-text');\n\n        items.forEach(item => {\n            item.addEventListener('click', () => {\n                const title = item.dataset.title;\n                const text = item.dataset.text;\n\n                if (title && boxTitle) {\n                    boxTitle.textContent = title;\n                }\n\n                if (text && boxText) {\n                    boxText.textContent = text;\n                }\n\n                \/\/ optioneel: active class\n                items.forEach(i => i.classList.remove('active'));\n                item.classList.add('active');\n            });\n        });\n    });\n<\/script>\n<section class=\"section-three-cards section-three-cards\" >\n    <div class=\"container pt-5 pb-5\">\n                    <div class=\"section-header\">\n                <h2 class=\"section-title\">\n                                            <span class=\"title-line-1\">Du papier<\/span>\n                                                                <span class=\"title-line-2\">au produit<\/span>\n                                    <\/h2>\n\n                                    <p class=\"section-description\">PaperWise est utilis\u00e9 comme papier et carton durables pour les emballages, l\u2019impression et le papier de copie. Pour tous ceux qui souhaitent contribuer \u00e0 un monde meilleur. <\/p>\n                            <\/div>\n        \n        <div class=\"row g-4\">\n                            <div class=\"col-12 col-md-6 col-lg-4\">\n                    <div class=\"card-item\">\n                                                    <div class=\"card-image\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/57347c400ba38ed9db47a87fbd8110f68085d977-scaled.jpg\"\n                                    alt=\"Emballages\"\n                                    loading=\"lazy\">\n                            <\/div>\n                        \n                        <div class=\"card-content\">\n                            <h3 class=\"card-title\">Emballages<\/h3>\n\n                                                            <p class=\"card-description\">PaperWise est le type de papier le plus durable pour les emballages alimentaires et non alimentaires, avec une gamme allant de 30 \u00e0 350 grammes.<\/p>\n                            \n                            <div class=\"card-cta\">\n                                <a href=\"https:\/\/paperwise.eu\/fr\/applications-demballage\/\"\n                                    target=\"\"\n                                    class=\"btn-primary-paperwise\">\n                                    <span>Voir les emballages<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\" \/>\n                                    <\/svg>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-4\">\n                    <div class=\"card-item\">\n                                                    <div class=\"card-image\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/97527532f22fca0d2f8a8b7de85fd5bcf3cb13ce-scaled.jpg\"\n                                    alt=\"Impressions\"\n                                    loading=\"lazy\">\n                            <\/div>\n                        \n                        <div class=\"card-content\">\n                            <h3 class=\"card-title\">Impressions<\/h3>\n\n                                                            <p class=\"card-description\">Des cartes aux flyers en passant par les livres : choisissez un papier ayant un impact environnemental moindre. Adieu les arbres, bonjour les r\u00e9sidus v\u00e9g\u00e9taux ! \r\n<\/p>\n                            \n                            <div class=\"card-cta\">\n                                <a href=\"https:\/\/paperwise.eu\/fr\/applications-dimpression\/\"\n                                    target=\"\"\n                                    class=\"btn-primary-paperwise\">\n                                    <span>Voir les impressions<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\" \/>\n                                    <\/svg>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"col-12 col-md-6 col-lg-4\">\n                    <div class=\"card-item\">\n                                                    <div class=\"card-image\">\n                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/0321bbbc4605345ba82949fa2d23c35342e4f345-scaled.jpg\"\n                                    alt=\"Papier de copie\"\n                                    loading=\"lazy\">\n                            <\/div>\n                        \n                        <div class=\"card-content\">\n                            <h3 class=\"card-title\">Papier de copie<\/h3>\n\n                                                            <p class=\"card-description\">Papier d\u2019impression durable, formats A4 et A3. En teintes blanc et naturel. Disponible imm\u00e9diatement en stock. Commandez facilement et rapidement.  <\/p>\n                            \n                            <div class=\"card-cta\">\n                                <a href=\"https:\/\/paperwise.eu\/fr\/applications-papier-de-copie\/\"\n                                    target=\"\"\n                                    class=\"btn-primary-paperwise\">\n                                    <span>Voir le papier de copie<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\" \/>\n                                    <\/svg>\n                                <\/a>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n<section class=\"section-certifications pt-4 pb-4 section-certifications\" >\n    <div class=\"certifications-green-box\">\n        <div class=\"container pt-4 pb-4\">\n            <div class=\"row\">\n                <!-- Left Column: Content -->\n                <div class=\"col-lg-7\">\n                    <div class=\"certifications-content\">\n                                                    <h2 class=\"section-title\">\n                                                                    <span class=\"title-line-1\">Vos<\/span>\n                                                                                                    <span class=\"title-line-2\">Avantages<\/span>\n                                                            <\/h2>\n                        \n                                                    <p class=\"intro-text\">Avec le papier issu de d\u00e9chets agricoles, vous contribuez positivement \u00e0 un monde meilleur et r\u00e9duisez votre impact sur le changement climatique. PaperWise est certifi\u00e9 pour le recyclage, le compostage et la s\u00e9curit\u00e9 alimentaire.  <\/p>\n                        \n                                                    <div class=\"usps-list\">\n                                                                    <div class=\"usp-item\">\n                                                                                    <div class=\"usp-icon\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/014a345025fd91a07348f337c954aba418f0cff5.png\"\n                                                     alt=\"\"\n                                                     loading=\"lazy\">\n                                            <\/div>\n                                                                                <div class=\"usp-content\">\n                                                                                            <div class=\"usp-title\">Mati\u00e8re premi\u00e8re secondaire<\/div>\n                                                                                                                                        <div class=\"usp-description\">Flux de r\u00e9sidus de l\u2019agriculture. Wise With Waste <\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                                                    <div class=\"usp-item\">\n                                                                                    <div class=\"usp-icon\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/089125452d1aeb86438cf14e7f6bc708cf329d73.png\"\n                                                     alt=\"\"\n                                                     loading=\"lazy\">\n                                            <\/div>\n                                                                                <div class=\"usp-content\">\n                                                                                            <div class=\"usp-title\">Circulaire<\/div>\n                                                                                                                                        <div class=\"usp-description\">Boucle ferm\u00e9e<\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                                                    <div class=\"usp-item\">\n                                                                                    <div class=\"usp-icon\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/68d30017a2502decc075c88436ae2f948e84022d.png\"\n                                                     alt=\"\"\n                                                     loading=\"lazy\">\n                                            <\/div>\n                                                                                <div class=\"usp-content\">\n                                                                                            <div class=\"usp-title\">Respectueux des arbres<\/div>\n                                                                                                                                        <div class=\"usp-description\">Fabriqu\u00e9 \u00e0 partir de r\u00e9sidus v\u00e9g\u00e9taux, ce qui permet de pr\u00e9server<br \/>\r\nles arbres<\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                                                    <div class=\"usp-item\">\n                                                                                    <div class=\"usp-icon\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/image-26.png\"\n                                                     alt=\"\"\n                                                     loading=\"lazy\">\n                                            <\/div>\n                                                                                <div class=\"usp-content\">\n                                                                                            <div class=\"usp-title\">\u00c9conomie de CO\u2082<\/div>\n                                                                                                                                        <div class=\"usp-description\">PaperWise a un impact environnemental plus faible que le papier issu des <br \/>\r\narbres et le papier recycl\u00e9<\/div>\n                                                                                    <\/div>\n                                    <\/div>\n                                                            <\/div>\n                        \n                                                    <div class=\"certifications-section\">\n                                                                    <div class=\"certified-icon\">\n                                        <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/certifications\/certified-icon.svg\"\n                                             alt=\"Certified\"\n                                             loading=\"lazy\">\n                                    <\/div>\n                                    <h3 class=\"certified-title\">Certifi\u00e9 pour<\/h3>\n                                \n                                                                    <ul class=\"certifications-list\">\n                                                                                    <li class=\"certification-item\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/certifications\/check-icon.svg\"\n                                                     alt=\"Check\"\n                                                     class=\"check-icon\"\n                                                     loading=\"lazy\">\n                                                <span>Recyclage (PTS)<\/span>\n                                            <\/li>\n                                                                                    <li class=\"certification-item\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/certifications\/check-icon.svg\"\n                                                     alt=\"Check\"\n                                                     class=\"check-icon\"\n                                                     loading=\"lazy\">\n                                                <span>Compostage domestique (DIN CERTCO)<\/span>\n                                            <\/li>\n                                                                                    <li class=\"certification-item\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/certifications\/check-icon.svg\"\n                                                     alt=\"Check\"\n                                                     class=\"check-icon\"\n                                                     loading=\"lazy\">\n                                                <span>Compostage industriel (EN 13432)<\/span>\n                                            <\/li>\n                                                                                    <li class=\"certification-item\">\n                                                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/certifications\/check-icon.svg\"\n                                                     alt=\"Check\"\n                                                     class=\"check-icon\"\n                                                     loading=\"lazy\">\n                                                <span>Contact alimentaire direct (ISEGA)<\/span>\n                                            <\/li>\n                                                                            <\/ul>\n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n\n                <!-- Right Column: Plant (overflows the green box) -->\n                <div class=\"col-lg-5\">\n                    <div class=\"plant-wrapper\">\n                        <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/themes\/allroundweb-theme\/assets\/img\/impact\/sugarcane-plant.png\"\n                             alt=\"Sugarcane Plant\"\n                             class=\"sugarcane-plant\"\n                             loading=\"lazy\">\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"section-image-content pt-2 pb-4 mt-1 section-image-content image-left\" >\n    <div class=\"container pt-2 pb-4\">\n        <div class=\"row align-items-center gx-5\">\n                            <!-- Image Left -->\n                <div class=\"col-lg-7\">\n                    <div class=\"image-wrapper\">\n                        <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/Rectangle-138.png\"\n                             alt=\"\"\n                             class=\"section-image\"\n                             loading=\"lazy\">\n                    <\/div>\n                <\/div>\n\n                <!-- Content Right -->\n                <div class=\"col-lg-5\">\n                    <div class=\"content-wrapper\">\n                                                    <h2 class=\"section-title\">\n                                                                    <span class=\"title-line-1\">Communication<\/span>\n                                                                                            <\/h2>\n                        \n                                                    <div class=\"section-description\">\n                                Montrez que vous contribuez consciemment \u00e0 un monde meilleur. PaperWise vous aide dans votre communication sur la durabilit\u00e9. Sur les emballages, les imprim\u00e9s et en ligne.                              <\/div>\n                        \n                                                    <div class=\"button-wrapper\">\n                                <a href=\"https:\/\/paperwise.eu\/fr\/outil-de-communication\/\"\n                                   target=\"_self\"\n                                   class=\"btn-primary-paperwise\">\n                                    <span>Logos<\/span>\n                                    <svg width=\"14\" height=\"12\" viewBox=\"0 0 14 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                        <path d=\"M13.5303 6.53033C13.8232 6.23744 13.8232 5.76256 13.5303 5.46967L8.75736 0.696699C8.46447 0.403806 7.98959 0.403806 7.6967 0.696699C7.40381 0.989593 7.40381 1.46447 7.6967 1.75736L11.9393 6L7.6967 10.2426C7.40381 10.5355 7.40381 11.0104 7.6967 11.3033C7.98959 11.5962 8.46447 11.5962 8.75736 11.3033L13.5303 6.53033ZM0 6.75H13V5.25H0V6.75Z\" fill=\"currentColor\"\/>\n                                    <\/svg>\n                                <\/a>\n                            <\/div>\n                                            <\/div>\n                    <div class=\"infographic-arrow arrow-5\">\n                        <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2026\/02\/teal-arrow.svg\"\/>   \n                    <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18997","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avantages - Paperwise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/fr\/avantages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avantages - Paperwise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/fr\/avantages\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:17:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/avantages\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/avantages\\\/\",\"name\":\"Avantages - Paperwise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\"},\"datePublished\":\"2025-11-14T14:48:49+00:00\",\"dateModified\":\"2026-07-08T12:17:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/avantages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/fr\\\/avantages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/avantages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avantages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avantages - Paperwise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/fr\/avantages\/","og_locale":"fr_FR","og_type":"article","og_title":"Avantages - Paperwise","og_url":"https:\/\/paperwise.eu\/fr\/avantages\/","og_site_name":"Paperwise","article_modified_time":"2026-07-08T12:17:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/fr\/avantages\/","url":"https:\/\/paperwise.eu\/fr\/avantages\/","name":"Avantages - Paperwise","isPartOf":{"@id":"https:\/\/paperwise.eu\/fr\/#website"},"datePublished":"2025-11-14T14:48:49+00:00","dateModified":"2026-07-08T12:17:50+00:00","breadcrumb":{"@id":"https:\/\/paperwise.eu\/fr\/avantages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/fr\/avantages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/fr\/avantages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/paperwise.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Avantages"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/fr\/#website","url":"https:\/\/paperwise.eu\/fr\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/pages\/18997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/comments?post=18997"}],"version-history":[{"count":2,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/pages\/18997\/revisions"}],"predecessor-version":[{"id":19400,"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/pages\/18997\/revisions\/19400"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/fr\/wp-json\/wp\/v2\/media?parent=18997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}