{"id":15272,"date":"2025-11-29T05:28:03","date_gmt":"2025-11-29T04:28:03","guid":{"rendered":"https:\/\/paperwise.eu\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/"},"modified":"2026-04-09T06:53:22","modified_gmt":"2026-04-09T04:53:22","slug":"scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales","status":"publish","type":"post","link":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/","title":{"rendered":"Scoop: papel de copia e impresi\u00f3n neutro en CO2 y sin \u00e1rboles, procedente de residuos vegetales"},"content":{"rendered":"\n<section class=\"section-hero-paperwise text-color-oscuro\" >\n    <div class=\"hero-background \" style=\"background-image: url('https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg');\">\n\n        \n        <div class=\"container-fluid h-100 pt-4 pb-4\">\n            <div class=\"row h-100\">\n                <div class=\"col-12 d-flex align-items-end\">\n                    <div class=\"hero-content\">\n                                                    <h1 class=\"hero-title\">\n                                <span class=\"hero-title-highlight\">Scoop: papel de copia e impresi\u00f3n neutro en<\/span> CO2 y sin \u00e1rboles, procedente de residuos vegetales                            <\/h1>\n                        \n                        \n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n<script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    \/\/ Vimeo can run immediately since the SDK loads synchronously enough\n    const heroVideos = document.querySelectorAll('.hero-video-wrapper iframe');\n    heroVideos.forEach(iframe => {\n        if (iframe.src.includes('vimeo.com')) {\n            const player = new Vimeo.Player(iframe);\n            player.getDuration().then(duration => {\n                player.on('timeupdate', data => {\n                    if (data.seconds >= duration - 1) {\n                        player.setCurrentTime(0).then(() => player.play());\n                    }\n                });\n            });\n        }\n    });\n\n    \/\/ Collect YouTube iframes to initialize once the API is ready\n    window._ytHeroIframes = document.querySelectorAll('.hero-video-wrapper iframe[src*=\"youtube.com\"]');\n});\n\n\/\/ This is called automatically by the YouTube API once it's fully loaded\nwindow.onYouTubeIframeAPIReady = function() {\n    if (!window._ytHeroIframes) return;\n\n    window._ytHeroIframes.forEach(iframe => {\n        const videoId = iframe.src.match(\/embed\\\/([^?&]+)\/)[1];\n        const parent = iframe.parentNode;\n        iframe.remove();\n\n        const ytDiv = document.createElement('div');\n        ytDiv.id = 'yt-hero-' + Math.floor(Math.random() * 10000);\n        ytDiv.classList.add('hero-video');\n        parent.appendChild(ytDiv);\n\n        new YT.Player(ytDiv.id, {\n            videoId: videoId,\n            playerVars: {\n                autoplay: 1,\n                controls: 0,\n                loop: 1,\n                playlist: videoId,\n                mute: 1,\n                modestbranding: 1,\n                disablekb: 1,\n                playsinline: 1\n            },\n            events: {\n                onReady: function(event) {\n                    const duration = event.target.getDuration();\n                    setInterval(() => {\n                        const current = event.target.getCurrentTime();\n                        if (current >= duration - 1) {\n                            event.target.seekTo(0);\n                            event.target.playVideo();\n                        }\n                    }, 800);\n                }\n            }\n        });\n    });\n};\n<\/script>\n<section id=\"section-text-block_097905f9d97862afa3bfa341db08c75d\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>PaperWise presenta papel de copia e impresi\u00f3n sin blanquear y neutro en CO2, fabricado con residuos vegetales; tallos y hojas sobrantes de la agricultura. Esto hace que el papel de copia PaperWise est\u00e9 100% libre de \u00e1rboles. La ventaja de nuestra innovaci\u00f3n en papel es su impacto medioambiental extremadamente bajo y su m\u00e1xima contribuci\u00f3n a los Objetivos de Desarrollo Sostenible (ODS) de las Naciones Unidas. \u00bfTe preguntas c\u00f3mo contribuye a ello el papel de impresi\u00f3n PaperWise?   <\/p>\n<h2>\u00bfPor qu\u00e9 imprimir papel fabricado con residuos vegetales procedentes de la agricultura?<\/h2>\n<p>\u00abEs s\u00f3lo papel de copia\u00bb, pensar\u00e1s. Y lo es. Precisamente porque es un producto tan normal y de uso tan com\u00fan, a menudo no te paras a pensar en el impacto que puedes tener eligiendo una variante ecol\u00f3gica. El papel de impresi\u00f3n se utiliza principalmente para leer informaci\u00f3n de forma r\u00e1pida y agradable y, si se desea, para tomar notas. Todo el mundo lo utiliza, en casa y\/o en el trabajo, y precisamente por eso el papel de copia e impresi\u00f3n tiene tanto impacto en el medio ambiente. La mayor parte del papel de copia se fabrica con \u00e1rboles cuyo tiempo de crecimiento oscila entre 15 y 80 a\u00f1os. Se necesitan tantos a\u00f1os para que los \u00e1rboles crezcan antes de ser talados, mientras que la vida \u00fatil del papel de impresi\u00f3n es relativamente muy corta. En PaperWise demostramos que esto se puede hacer de otra manera. El <a href=\"https:\/\/paperwise.eu\/shop\/eind-producten\/paperwise-natural-kopieerpapier-a4-210x297mm-72-g-m%c2%b2-5x500-vellen\/\">papel PaperWise Natural Copy &amp; Printing A4 72g<\/a>, fabricado \u00edntegramente con residuos vegetales procedentes de la agricultura, ofrece la soluci\u00f3n para las personas y empresas que buscan el papel de copia e impresi\u00f3n m\u00e1s respetuoso con el medio ambiente y sostenible.       <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-33.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_c6d5b5e2c2bc038e1d6282dbc29682e9\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>El impacto medioambiental del papel de copia e impresi\u00f3n<\/h2>\n<p>En Europa utilizamos 75 millones de toneladas de papel y cart\u00f3n al a\u00f1o. El 55% se recicla y el 45% restante se fabrica a partir de \u00e1rboles (Fuente: <a href=\"https:\/\/cepi.net\/\">CEPI<\/a>). No te escandalices, \u00a1pero para ello talamos anualmente 265 millones de \u00e1rboles! La superficie forestal necesaria para ello requiere una superficie mayor que la del Reino Unido o 6 veces la de Holanda. El consumo mundial de papel y cart\u00f3n es cuatro veces mayor (Fuente: <a href=\"https:\/\/cepi.net\/\">CEPI<\/a>). Si a esto a\u00f1adimos que la poblaci\u00f3n mundial sigue creciendo y con ella el consumo de papel, todo el mundo comprende que el uso de la tierra para la silvicultura es una gran amenaza para la industria papelera y no tiene futuro.     <\/p>\n<h2>Papel circular para impresi\u00f3n y copia<\/h2>\n<p>\u00bfPor qu\u00e9 se queman los residuos vegetales (tallos y hojas) sobrantes de la cosecha agr\u00edcola y no se reutilizan como materia prima para papel de copia e impresi\u00f3n? \u00bfQu\u00e9 podemos mejorar del papel de copia e impresi\u00f3n existente? Preguntas que nos planteamos. PaperWise se ha centrado plenamente en la econom\u00eda circular desde nuestro lanzamiento en 2015. Queremos maximizar nuestra contribuci\u00f3n al mayor n\u00famero posible de ODS. As\u00ed naci\u00f3 la idea de desarrollar una nueva generaci\u00f3n de papel de copia con el menor impacto medioambiental y crear un caldo de cultivo para una mayor prosperidad en los pa\u00edses en desarrollo.Contribuci\u00f3n a los ODS con el papel de copia e impresi\u00f3n PaperWisePaperWise ha elegido deliberadamente utilizar residuos vegetales procedentes de la agricultura para todas las calidades de papel. Esto nos permite contribuir a los 17 objetivos de sostenibilidad de las Naciones Unidas:      <\/p>\n<h2>VALOR M\u00daLTIPLE DE LOS RESIDUOS<\/h2>\n<p>Los residuos vegetales de la agricultura crean ingresos adicionales para los agricultores pobres. Esto aumenta su prosperidad, incrementa la seguridad alimentaria, hace asequibles la atenci\u00f3n m\u00e9dica y la educaci\u00f3n. Disminuye la desigualdad econ\u00f3mica y sienta las bases de comunidades seguras y sostenibles.  <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-28.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_7fc6abe06bb759782820062f6c2b286b\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>IGUALDAD, RESPETO Y COLABORACI\u00d3N PARA UNA SOCIEDAD SOSTENIBLE<\/h2>\n<p>La base de unas pr\u00e1cticas empresariales justas y de una sociedad pac\u00edfica y justa empieza por la concienciaci\u00f3n. Respeto e igualdad entre hombres, mujeres, empresas y organizaciones. Conectando unos con otros. Construyendo juntos, como socios, una industrializaci\u00f3n y unas infraestructuras sostenibles para todos.   <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-29.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_520f030b35ff85a4094945c20a9197ad\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>SABIO CON LOS RESIDUOS<\/h2>\n<p>La celulosa, materia prima del papel y el cart\u00f3n, puede extraerse de los residuos agr\u00edcolas utilizando menos energ\u00eda, productos qu\u00edmicos y agua. Tanto los alimentos como la materia prima del papel proceden de la misma tierra y planta. La seguridad, la energ\u00eda verde y los procesos en los que se utilizan residuos como materia prima mantienen el equilibrio de los sistemas ecol\u00f3gicos.  <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-30.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_078808c8888e455f31ebc387c652ada3\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>El papel de copia PaperWise Natural aporta valor a\u00f1adido<\/h2>\n<p>Al elegir PaperWise contribuyes a que los agricultores de los pa\u00edses en desarrollo obtengan ingresos extra, pero tambi\u00e9n contribuyes a un aire limpio al eliminar la necesidad de quemar residuos agr\u00edcolas en la tierra. El papel PaperWise Natural sin blanquear tiene un color marr\u00f3n claro, lo que le da un aspecto sostenible. Los textos son muy agradables y tranquilos de leer. El papel de copia PaperWise Natural de 72 gramos tiene un tacto tan firme como el papel blanco blanqueado de 80 gramos procedente de \u00e1rboles, pero es un 10% m\u00e1s ligero, otra ventaja de no blanquear el papel. El embalaje del papel de copia PaperWise Natural est\u00e1 hecho del mismo material, con lo que se aplica plenamente la sostenibilidad. Otra primicia son las pr\u00e1cticas asas recortadas de la caja, que facilitan mucho el levantamiento y el transporte.     <\/p>\n<h2>Todas las ventajas de un vistazo:<\/h2>\n<p>100% residuos vegetales<br \/>\n100% sin \u00e1rboles<br \/>\n100% CO2 neutro<br \/>\n100% reciclable<br \/>\n100% de ahorro en el uso del suelo<\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n\n<div class=\"section-full-width-image-wrapper\">\n    <section class=\"section-full-width-image section-full-width-image height-medium parallax-enabled\" >\n                    <div class=\"image-container\">\n                <img decoding=\"async\" src=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-16.jpg\"\n                     alt=\"\"\n                     class=\"full-width-image\"\n                     loading=\"lazy\">\n            <\/div>\n            <\/section>\n\n    <\/div>\n\n<script>\n(function() {\n    const parallaxSection = document.querySelector('.section-full-width-image.parallax-enabled');\n    if (!parallaxSection) return;\n\n    const parallaxImage = parallaxSection.querySelector('.full-width-image');\n    if (!parallaxImage) return;\n\n    function updateParallax() {\n        const rect = parallaxSection.getBoundingClientRect();\n        const windowHeight = window.innerHeight;\n\n        \/\/ Check if section is in viewport\n        if (rect.bottom > 0 && rect.top < windowHeight) {\n            \/\/ Calculate scroll progress (0 to 1) relative to viewport\n            const scrollProgress = (windowHeight - rect.top) \/ (windowHeight + rect.height);\n\n            \/\/ Move image from -20% to +20% based on scroll progress\n            const movement = (scrollProgress - 0.5) * 40; \/\/ -20 to +20\n\n            parallaxImage.style.transform = `translate3d(0, ${movement}%, 0)`;\n        }\n    }\n\n    \/\/ Throttle scroll event for better performance\n    let ticking = false;\n    window.addEventListener('scroll', function() {\n        if (!ticking) {\n            window.requestAnimationFrame(function() {\n                updateParallax();\n                ticking = false;\n            });\n            ticking = true;\n        }\n    });\n\n    \/\/ Initial call\n    updateParallax();\n})();\n<\/script>\n\n<section id=\"section-text-block_8fa339a1223f266a72494cf0fe968891\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <h2>\u00bfTienes curiosidad? Experimenta y prueba: <\/h2>\n<p>Si quieres probarlo t\u00fa mismo, <a href=\"https:\/\/paperwise.eu\/shop\/eind-producten\/paperwise-natural-kopieerpapier-a4-210x297mm-72-g-m%c2%b2-5x500-vellen\/\">haz clic aqu\u00ed<\/a> y prueba PaperWise Natural Copy &amp;Printing A4 72g caja 5\u00d7500 hojas. Disponible a partir de 30,11 euros por caja cuando se pide por pal\u00e9 completo de 48 cajas (sin IVA ni gastos de env\u00edo). Cuantas m\u00e1s cajas pidas, menor ser\u00e1 el precio por caja. \u00a1Feliz impresi\u00f3n!   <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":15277,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[272],"tags":[322],"class_list":["post-15272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-co2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible<\/title>\n<meta name=\"description\" content=\"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible\" \/>\n<meta property=\"og:description\" content=\"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-29T04:28:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T04:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"romano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/\"},\"author\":{\"name\":\"romano\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"headline\":\"Scoop: papel de copia e impresi\u00f3n neutro en CO2 y sin \u00e1rboles, procedente de residuos vegetales\",\"datePublished\":\"2025-11-29T04:28:03+00:00\",\"dateModified\":\"2026-04-09T04:53:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/\"},\"wordCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg\",\"keywords\":[\"CO2\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/\",\"name\":\"Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg\",\"datePublished\":\"2025-11-29T04:28:03+00:00\",\"dateModified\":\"2026-04-09T04:53:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"description\":\"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg\",\"contentUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg\",\"width\":1920,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/pagina-de-inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scoop: papel de copia e impresi\u00f3n neutro en CO2 y sin \u00e1rboles, procedente de residuos vegetales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\",\"name\":\"romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"caption\":\"romano\"},\"url\":\"https:\\\/\\\/paperwise.eu\\\/es\\\/author\\\/romano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible","description":"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/","og_locale":"es_ES","og_type":"article","og_title":"Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible","og_description":"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.","og_url":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/","og_site_name":"Paperwise","article_published_time":"2025-11-29T04:28:03+00:00","article_modified_time":"2026-04-09T04:53:22+00:00","og_image":[{"width":1920,"height":786,"url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg","type":"image\/jpeg"}],"author":"romano","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"romano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#article","isPartOf":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/"},"author":{"name":"romano","@id":"https:\/\/paperwise.eu\/es\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"headline":"Scoop: papel de copia e impresi\u00f3n neutro en CO2 y sin \u00e1rboles, procedente de residuos vegetales","datePublished":"2025-11-29T04:28:03+00:00","dateModified":"2026-04-09T04:53:22+00:00","mainEntityOfPage":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/"},"wordCount":17,"image":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg","keywords":["CO2"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/","url":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/","name":"Papel de impresi\u00f3n ecol\u00f3gico | Papel de copia sostenible","isPartOf":{"@id":"https:\/\/paperwise.eu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#primaryimage"},"image":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg","datePublished":"2025-11-29T04:28:03+00:00","dateModified":"2026-04-09T04:53:22+00:00","author":{"@id":"https:\/\/paperwise.eu\/es\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"description":"El papel de copia e impresi\u00f3n m\u00e1s ecol\u00f3gico y sostenible: 100% libre de \u00e1rboles, fabricado a partir de residuos vegetales, neutro en CO2 y totalmente reciclable.","breadcrumb":{"@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#primaryimage","url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg","contentUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/11\/paperwise-sustainable-paper-board-agri-wise-with-waste-blog-images-22.jpg","width":1920,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/es\/scoop-papel-de-copia-e-impresion-neutro-en-co2-y-sin-arboles-procedente-de-residuos-vegetales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/paperwise.eu\/es\/pagina-de-inicio\/"},{"@type":"ListItem","position":2,"name":"Scoop: papel de copia e impresi\u00f3n neutro en CO2 y sin \u00e1rboles, procedente de residuos vegetales"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/es\/#website","url":"https:\/\/paperwise.eu\/es\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/paperwise.eu\/es\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e","name":"romano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","caption":"romano"},"url":"https:\/\/paperwise.eu\/es\/author\/romano\/"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/posts\/15272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/comments?post=15272"}],"version-history":[{"count":1,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/posts\/15272\/revisions"}],"predecessor-version":[{"id":15284,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/posts\/15272\/revisions\/15284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/media\/15277"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/media?parent=15272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/categories?post=15272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paperwise.eu\/es\/wp-json\/wp\/v2\/tags?post=15272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}