{"id":15206,"date":"2025-12-01T06:30:21","date_gmt":"2025-12-01T05:30:21","guid":{"rendered":"https:\/\/paperwise.eu\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/"},"modified":"2026-04-09T06:53:16","modified_gmt":"2026-04-09T04:53:16","slug":"klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85","status":"publish","type":"post","link":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/","title":{"rendered":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85%"},"content":{"rendered":"\n<section class=\"section-hero-paperwise text-color-Licht\" >\n    <div class=\"hero-background \" style=\"background-image: url('https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg');\">\n\n        \n        <div class=\"container-fluid h-100 pt-4 pb-4\">\n            <div class=\"row h-100\">\n                <div class=\"col-12 d-flex align-items-end\">\n                    <div class=\"hero-content\">\n                                                    <h1 class=\"hero-title\">\n                                <span class=\"hero-title-highlight\">Klug mit Abfall-Weisheiten: ANTEIL an<\/span> landwirtschaftlichen Abf\u00e4llen steigt auf 85%                            <\/h1>\n                        \n                        \n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<script src=\"https:\/\/www.youtube.com\/iframe_api\"><\/script>\n<script src=\"https:\/\/player.vimeo.com\/api\/player.js\"><\/script>\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n    \/\/ Vimeo can run immediately since the SDK loads synchronously enough\n    const heroVideos = document.querySelectorAll('.hero-video-wrapper iframe');\n    heroVideos.forEach(iframe => {\n        if (iframe.src.includes('vimeo.com')) {\n            const player = new Vimeo.Player(iframe);\n            player.getDuration().then(duration => {\n                player.on('timeupdate', data => {\n                    if (data.seconds >= duration - 1) {\n                        player.setCurrentTime(0).then(() => player.play());\n                    }\n                });\n            });\n        }\n    });\n\n    \/\/ Collect YouTube iframes to initialize once the API is ready\n    window._ytHeroIframes = document.querySelectorAll('.hero-video-wrapper iframe[src*=\"youtube.com\"]');\n});\n\n\/\/ This is called automatically by the YouTube API once it's fully loaded\nwindow.onYouTubeIframeAPIReady = function() {\n    if (!window._ytHeroIframes) return;\n\n    window._ytHeroIframes.forEach(iframe => {\n        const videoId = iframe.src.match(\/embed\\\/([^?&]+)\/)[1];\n        const parent = iframe.parentNode;\n        iframe.remove();\n\n        const ytDiv = document.createElement('div');\n        ytDiv.id = 'yt-hero-' + Math.floor(Math.random() * 10000);\n        ytDiv.classList.add('hero-video');\n        parent.appendChild(ytDiv);\n\n        new YT.Player(ytDiv.id, {\n            videoId: videoId,\n            playerVars: {\n                autoplay: 1,\n                controls: 0,\n                loop: 1,\n                playlist: videoId,\n                mute: 1,\n                modestbranding: 1,\n                disablekb: 1,\n                playsinline: 1\n            },\n            events: {\n                onReady: function(event) {\n                    const duration = event.target.getDuration();\n                    setInterval(() => {\n                        const current = event.target.getCurrentTime();\n                        if (current >= duration - 1) {\n                            event.target.seekTo(0);\n                            event.target.playVideo();\n                        }\n                    }, 800);\n                }\n            }\n        });\n    });\n};\n<\/script>\n<section id=\"section-text-block_0dca1af297b032d91fedecd86c4dc9f6\" class=\"section section-text\">\n    <div class=\"container\">\n        <div class=\"section-text__wrapper text-align-left\">\n\n            \n                            <div class=\"section-text__content\">\n                    <p>Der Anteil an landwirtschaftlichen Abf\u00e4llen in PaperWise White, dem wei\u00dfen, nachhaltigen grafischen PaperWise-Papier in 80-90 und 110g, ist auf &gt;85% gestiegen. Bei unserer Markteinf\u00fchrung im Jahr 2015 lag der Anteil an pflanzlichen Reststoffen noch bei 55%. Gemeinsam mit der Papierfabrik ist es PaperWise also gelungen, den Anteil der landwirtschaftlichen Abf\u00e4lle deutlich zu erh\u00f6hen! Juhu! In unserem Bestreben, die Papierindustrie nachhaltiger zu machen, arbeitet PaperWise kontinuierlich an Innovationen und Verbesserungen. Wie haben wir diesen Schritt erreicht?     <\/p>\n<p>Zun\u00e4chst zur\u00fcck zu unserer Mission: Wir wollen sowohl einen sozialen als auch einen \u00f6kologischen Nutzen erzielen, indem wir landwirtschaftliche Abf\u00e4lle nicht mehr verbrennen, sondern ihnen ein 2. Die Sache ist die: Die armen Bauern in den Entwicklungsl\u00e4ndern erhalten nur noch Geld f\u00fcr die Lebensmittel, die auf den Nahrungspflanzen wachsen, d.h. f\u00fcr den essbaren Teil der Pflanze. Das sind nur 20% der gesamten Pflanze! Die restlichen 80%, St\u00e4ngel und Bl\u00e4tter, werden meist verbrannt, was zu Umweltverschmutzung, Verschlechterung der Bodenqualit\u00e4t und Smogbildung f\u00fchrt.   <\/p>\n<p>Aber das gilt nicht f\u00fcr die Landwirte, die f\u00fcr die Rohstoffe von PaperWise verantwortlich sind. Die landwirtschaftlichen Abf\u00e4lle dieser Landwirte werden nicht verbrannt, sondern gesammelt, um als Rohstoff f\u00fcr PaperWise Papier und Karton verwendet zu werden. Das bedeutet, dass diese Landwirte f\u00fcr 100% der Pflanze bezahlt werden! Ein h\u00f6herer Ertrag f\u00fcr die Landwirte tr\u00e4gt zu mehr Wohlstand bei. Wenn Sie sich also f\u00fcr PaperWise-Papier und -Karton f\u00fcr Ihre nachhaltigen Verpackungen und Druckerzeugnisse entscheiden oder PaperWise im B\u00fcro verwenden (z.B. umweltfreundliches <a href=\"https:\/\/paperwise.eu\/shop\/?_sfm_artikelen=kopieerpapier%20voor%20kantoor\">Druck- und Kopierpapier<\/a>, <a href=\"https:\/\/paperwise.eu\/shop\/?_sfm_artikelen=notitieblokken%20voor%20kantoor\">Schreibbl\u00f6cke<\/a> und <a href=\"https:\/\/paperwise.eu\/shop\/?_sfm_artikelen=bekers%20voor%20kantoor\">Trinkbecher<\/a> ), geben Sie den 80% Pflanzenresten (St\u00e4ngeln und Bl\u00e4ttern) einen Wert und tragen zu sozialen und \u00f6kologischen Vorteilen bei!    <\/p>\n<h2>Vor welcher Herausforderung stehen wir noch?<\/h2>\n<p>Unser Ziel ist es, st\u00e4ndig innovativ zu sein und uns zu verbessern. Wir sind sehr stolz darauf, dass es uns gelungen ist, den Anteil der landwirtschaftlichen Abf\u00e4lle in PaperWise White von 55% auf &gt; 85% zu erh\u00f6hen, aber es gibt noch Raum f\u00fcr Verbesserungen. Gl\u00fccklicherweise besteht <a href=\"https:\/\/paperwise.eu\/shop\/?_sfm_kleur=naturel\">PaperWise Natural<\/a>, unser ungebleichtes hellbraunes Papier und Karton, bereits zu 100% aus landwirtschaftlichen Abf\u00e4llen. Aber das ist noch nicht alles. PaperWise selbst hat noch keinen Einfluss auf die Kette vom Landwirt zu PaperWise. Diese Kontakte laufen \u00fcber die Papierfabriken und die Bauerngenossenschaften. PaperWise m\u00f6chte Einfluss auf die Kette gewinnen, um gemeinsam mit den armen Landwirten (Genossenschaften) eine Politik zu machen, die den Wohlstand und das Wohlergehen dieser Bev\u00f6lkerungsgruppe f\u00f6rdert.      <\/p>\n<h2>Mit PaperWise gestalten Sie eine verantwortungsvolle Zukunft<\/h2>\n<p>Helfen Sie uns und verwenden Sie PaperWise f\u00fcr all Ihr umweltfreundliches Verpackungs-, Druck- und B\u00fcropapier. Auf diese Weise k\u00f6nnen wir gemeinsam unsere Gesellschaft nachhaltiger gestalten und zu den <a href=\"https:\/\/www.undp.org\/content\/undp\/en\/home\/sustainable-development-goals.html\">Zielen f\u00fcr nachhaltige Entwicklung<\/a> der Vereinten Nationen beitragen. Gemeinsam klug mit Abfall!  <\/p>\n                <\/div>\n            \n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":15209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[270],"tags":[319],"class_list":["post-15206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","tag-organisation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/\" \/>\n<meta property=\"og:site_name\" content=\"Paperwise\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T05:30:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T04:53:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"romano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/\"},\"author\":{\"name\":\"romano\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"headline\":\"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85%\",\"datePublished\":\"2025-12-01T05:30:21+00:00\",\"dateModified\":\"2026-04-09T04:53:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/\"},\"wordCount\":10,\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg\",\"keywords\":[\"Organisation\"],\"articleSection\":[\"Nachrichten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/\",\"name\":\"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg\",\"datePublished\":\"2025-12-01T05:30:21+00:00\",\"dateModified\":\"2026-04-09T04:53:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#primaryimage\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg\",\"contentUrl\":\"https:\\\/\\\/paperwise.eu\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg\",\"width\":2200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/\",\"name\":\"Paperwise\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/#\\\/schema\\\/person\\\/8795b3f325bbd0bd99ae85bbea26ad2e\",\"name\":\"romano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g\",\"caption\":\"romano\"},\"url\":\"https:\\\/\\\/paperwise.eu\\\/de\\\/author\\\/romano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/","og_locale":"de_DE","og_type":"article","og_title":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise","og_url":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/","og_site_name":"Paperwise","article_published_time":"2025-12-01T05:30:21+00:00","article_modified_time":"2026-04-09T04:53:16+00:00","og_image":[{"width":2200,"height":900,"url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg","type":"image\/jpeg"}],"author":"romano","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"romano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#article","isPartOf":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/"},"author":{"name":"romano","@id":"https:\/\/paperwise.eu\/de\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"headline":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85%","datePublished":"2025-12-01T05:30:21+00:00","dateModified":"2026-04-09T04:53:16+00:00","mainEntityOfPage":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/"},"wordCount":10,"image":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg","keywords":["Organisation"],"articleSection":["Nachrichten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/","url":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/","name":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85% - Paperwise","isPartOf":{"@id":"https:\/\/paperwise.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#primaryimage"},"image":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#primaryimage"},"thumbnailUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg","datePublished":"2025-12-01T05:30:21+00:00","dateModified":"2026-04-09T04:53:16+00:00","author":{"@id":"https:\/\/paperwise.eu\/de\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e"},"breadcrumb":{"@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#primaryimage","url":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg","contentUrl":"https:\/\/paperwise.eu\/wp-content\/uploads\/2025\/12\/paperwise-renewable-recourses-paper-board-white-agricultural-waste.jpg","width":2200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/paperwise.eu\/de\/klug-mit-abfall-weisheiten-anteil-an-landwirtschaftlichen-abfaellen-steigt-auf-85\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/paperwise.eu\/de\/homepage\/"},{"@type":"ListItem","position":2,"name":"Klug mit Abfall-Weisheiten: ANTEIL an landwirtschaftlichen Abf\u00e4llen steigt auf 85%"}]},{"@type":"WebSite","@id":"https:\/\/paperwise.eu\/de\/#website","url":"https:\/\/paperwise.eu\/de\/","name":"Paperwise","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperwise.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/paperwise.eu\/de\/#\/schema\/person\/8795b3f325bbd0bd99ae85bbea26ad2e","name":"romano","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1088d66ec0cbb86d1f51d63deb3022acd3d470c3fa7de3b2bf2b7898ed286a14?s=96&d=mm&r=g","caption":"romano"},"url":"https:\/\/paperwise.eu\/de\/author\/romano\/"}]}},"_links":{"self":[{"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/posts\/15206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/comments?post=15206"}],"version-history":[{"count":1,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/posts\/15206\/revisions"}],"predecessor-version":[{"id":15211,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/posts\/15206\/revisions\/15211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/media\/15209"}],"wp:attachment":[{"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/media?parent=15206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/categories?post=15206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paperwise.eu\/de\/wp-json\/wp\/v2\/tags?post=15206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}